{"id":13582,"date":"2026-08-27T09:50:17","date_gmt":"2026-08-27T07:50:17","guid":{"rendered":"https:\/\/www.baikowski.com\/?post_type=job_listing&#038;p=13582"},"modified":"2026-08-27T09:50:17","modified_gmt":"2026-08-27T07:50:17","slug":"conducteurtrice-de-secteur-f-h","status":"publish","type":"job_listing","link":"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/","title":{"rendered":"Conducteur(trice) de secteur F\/H"},"content":{"rendered":"<p>Leader mondial dans les produits min\u00e9raux fins pour les industries de pointe. En int\u00e9grant notre entreprise, qui a f\u00eat\u00e9 ses 120 ans, vous participez \u00e0 l\u2019histoire d\u2019une structure \u00e0 taille humaine, port\u00e9e par une forte ambition de croissance internationale ax\u00e9e sur des march\u00e9s de haute technologie.<\/p>\n<p>Rattach\u00e9 \u00e0 l\u2019Agent de maitrise post\u00e9, votre mission consiste \u00e0 surveiller et assurer le fonctionnement, sur le terrain, d\u2019une ou plusieurs unit\u00e9s de fabrication en respectant les instructions d\u2019exploitation et en suivant les consignes de fabrication, de qualit\u00e9, de s\u00e9curit\u00e9 et de protection de l&rsquo;environnement.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Vos principales missions \u00e0 la prise de poste : <\/strong><\/p>\n<ul>\n<li>R\u00e9aliser la production, la tra\u00e7abilit\u00e9, la gestion de la zone de stockage, les changements de gammes de produits sur des installations automatis\u00e9es ou semi-automatis\u00e9es dans le respect de la mise en \u0153uvre des mati\u00e8res 1\u00e8res, du planning de production et des indicateurs de performance.<\/li>\n<li>R\u00e9aliser le d\u00e9marrage, la mise en route et l&rsquo;arr\u00eat des installations<\/li>\n<li>Rendre compte de la marche des unit\u00e9s et des r\u00e9sultats obtenus en utilisant les documents rattach\u00e9s (feuilles de poste, cahier de consignes) \u00e0 sa fonction et lors de ses \u00e9changes avec ses liaisons hi\u00e9rarchiques et fonctionnelles (dans les passations de consignes, en cas de d\u00e9rives, etc\u2026) pour permettre la continuit\u00e9 du processus de fabrication.<\/li>\n<li>Effectuer les \u00e9chantillonnages des produits finis et semi finis et effectuer les autocontr\u00f4les analytiques selon le plan d\u00e9fini<\/li>\n<li>Assurer les rondes de fabrication et de s\u00e9curit\u00e9 (d\u00e9tection et identification des anomalies et disfonctionnements et des risques \u00e9ventuels)<\/li>\n<li>R\u00e9aliser les t\u00e2ches n\u00e9cessaires aux changements de produits<\/li>\n<li>Appliquer la proc\u00e9dure travaux sur le terrain (Diagnostiques de pannes, r\u00e9alisation des mises \u00e0 disposition, r\u00e9ceptions de chantiers, \u2026)<\/li>\n<li>Assurer la maintenance 1er niveau sur son secteur<\/li>\n<li>Assurer les op\u00e9rations de manutention\u00a0: laver les conteneurs et assurer leur mise \u00e0 disposition\u00a0; r\u00e9aliser les transferts de conteneurs, de palettes, de Big Bags, d&rsquo;un atelier \u00e0 l&rsquo;autre et approvisionner les lignes etc\u2026<\/li>\n<li>Garantir les bonnes conditions de maintien et de propret\u00e9 sur son p\u00e9rim\u00e8tre de responsabilit\u00e9<\/li>\n<li>Faire remonter les irritants et des suggestions d\u2019am\u00e9lioration de son poste de travail et des \u00e9quipements de production.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Profil recherch\u00e9<\/strong>\u00a0:<\/p>\n<ul>\n<li>Dipl\u00f4me type CAP\/BEP CAIC (Conduite d&rsquo;Appareil des Industries Chimiques) et\/ou 5 ans d\u2019exp\u00e9rience en industrie<\/li>\n<li>CACES R489 Cat.3 et 1B \u00e0 jour<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Conditions de travail<\/strong>\u00a0:<\/p>\n<ul>\n<li>Poste en CDI, \u00e0 pourvoir d\u00e8s que possible<\/li>\n<li>Horaire en 6&#215;4 (deux matins\u00a0; deux apr\u00e8s-midis\u00a0; deux nuits\u00a0; 4 jours de repos)<\/li>\n<\/ul>\n<p>Si cette opportunit\u00e9 s\u2019inscrit dans votre projet professionnel, alors rejoignez-nous ! Envoyez votre CV et votre lettre de motivation \u00e0 <a href=\"mailto:recrutement@baikowski.com\">recrutement@baikowski.com<\/a> en indiquant la r\u00e9f\u00e9rence \u00ab\u00a0Conducteur(trice) de secteur F\/H\u00a0\u00bb dans l&rsquo;objet du mail.<\/p>\n","protected":false},"author":1076,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_promoted":"","_job_location":"Poisy","_application":"isabelle.guy@baikowski.com","_filled":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[],"class_list":["post-13582","job_listing","type-job_listing","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conducteur(trice) de secteur F\/H - Baikowski\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Conducteur(trice) de secteur F\/H - Baikowski\u00ae\" \/>\n<meta name=\"twitter:description\" content=\"Leader mondial dans les produits min\u00e9raux fins pour les industries de pointe. En int\u00e9grant notre entreprise, qui a f\u00eat\u00e9 ses 120 ans, vous participez \u00e0 l\u2019histoire d\u2019une structure \u00e0 taille humaine, port\u00e9e par une forte ambition de croissance internationale ax\u00e9e sur des march\u00e9s de haute technologie. Rattach\u00e9 \u00e0 l\u2019Agent de maitrise post\u00e9, votre mission consiste [&hellip;]\" \/>\n<meta name=\"twitter:site\" content=\"@BaikowskiTeam\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/job\\\/conducteurtrice-de-secteur-f-h\\\/\",\"url\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/job\\\/conducteurtrice-de-secteur-f-h\\\/\",\"name\":\"Conducteur(trice) de secteur F\\\/H - Baikowski\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-08-27T07:50:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/job\\\/conducteurtrice-de-secteur-f-h\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/job\\\/conducteurtrice-de-secteur-f-h\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/job\\\/conducteurtrice-de-secteur-f-h\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conducteur(trice) de secteur F\\\/H\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/\",\"name\":\"Baikowski\u00ae\",\"description\":\"Your solution partner for fine minerals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/#organization\",\"name\":\"Baikowski\u00ae\",\"url\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.baikowski.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Baikowski_blocmarque_RVB_ok.jpg\",\"contentUrl\":\"https:\\\/\\\/www.baikowski.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Baikowski_blocmarque_RVB_ok.jpg\",\"width\":1977,\"height\":754,\"caption\":\"Baikowski\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/www.baikowski.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/BaikowskiTeam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/baikowski\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC8ypcOZkT7RxGf5HC_aW70g\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conducteur(trice) de secteur F\/H - Baikowski\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/","twitter_card":"summary_large_image","twitter_title":"Conducteur(trice) de secteur F\/H - Baikowski\u00ae","twitter_description":"Leader mondial dans les produits min\u00e9raux fins pour les industries de pointe. En int\u00e9grant notre entreprise, qui a f\u00eat\u00e9 ses 120 ans, vous participez \u00e0 l\u2019histoire d\u2019une structure \u00e0 taille humaine, port\u00e9e par une forte ambition de croissance internationale ax\u00e9e sur des march\u00e9s de haute technologie. Rattach\u00e9 \u00e0 l\u2019Agent de maitrise post\u00e9, votre mission consiste [&hellip;]","twitter_site":"@BaikowskiTeam","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/","url":"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/","name":"Conducteur(trice) de secteur F\/H - Baikowski\u00ae","isPartOf":{"@id":"https:\/\/www.baikowski.com\/fr\/#website"},"datePublished":"2026-08-27T07:50:17+00:00","breadcrumb":{"@id":"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.baikowski.com\/fr\/job\/conducteurtrice-de-secteur-f-h\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.baikowski.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Conducteur(trice) de secteur F\/H"}]},{"@type":"WebSite","@id":"https:\/\/www.baikowski.com\/fr\/#website","url":"https:\/\/www.baikowski.com\/fr\/","name":"Baikowski\u00ae","description":"Your solution partner for fine minerals","publisher":{"@id":"https:\/\/www.baikowski.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baikowski.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.baikowski.com\/fr\/#organization","name":"Baikowski\u00ae","url":"https:\/\/www.baikowski.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.baikowski.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.baikowski.com\/wp-content\/uploads\/2020\/10\/Baikowski_blocmarque_RVB_ok.jpg","contentUrl":"https:\/\/www.baikowski.com\/wp-content\/uploads\/2020\/10\/Baikowski_blocmarque_RVB_ok.jpg","width":1977,"height":754,"caption":"Baikowski\u00ae"},"image":{"@id":"https:\/\/www.baikowski.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/BaikowskiTeam","https:\/\/www.linkedin.com\/company\/baikowski","https:\/\/www.youtube.com\/channel\/UC8ypcOZkT7RxGf5HC_aW70g"]}]}},"_links":{"self":[{"href":"https:\/\/www.baikowski.com\/fr\/wp-json\/wp\/v2\/job-listings\/13582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baikowski.com\/fr\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.baikowski.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.baikowski.com\/fr\/wp-json\/wp\/v2\/users\/1076"}],"wp:attachment":[{"href":"https:\/\/www.baikowski.com\/fr\/wp-json\/wp\/v2\/media?parent=13582"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.baikowski.com\/fr\/wp-json\/wp\/v2\/job-types?post=13582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}